{"id":28976,"date":"2022-03-09T11:37:52","date_gmt":"2022-03-09T10:37:52","guid":{"rendered":"https:\/\/rookieslash.org\/?page_id=28976"},"modified":"2026-04-29T14:03:17","modified_gmt":"2026-04-29T12:03:17","slug":"nos-activites-geneve","status":"publish","type":"page","link":"https:\/\/rookieslash.org\/en\/nos-activites-geneve\/","title":{"rendered":"Nos Activit\u00e9s \u00e0 Gen\u00e8ve"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbHeader\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(165,206,199,0.6) 0%|#151f33 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bbrgba(165,206,199,0.6)\u00a0\u00bb background_color_gradient_end=\u00a0\u00bb#151f33&Prime; background_image=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2022\/03\/IMG_0334-scaled.jpg\u00a0\u00bb min_height=\u00a0\u00bb400px\u00a0\u00bb custom_padding=\u00a0\u00bb5vw||5vw||true|false\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay: flex;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb background_color_gradient_start__hover=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_start__hover_enabled=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_end__hover=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_end__hover_enabled=\u00a0\u00bb#29c4a9&Prime; use_background_color_gradient__hover=\u00a0\u00bboff\u00a0\u00bb use_background_color_gradient__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_type__hover=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_type__hover_enabled=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_direction__hover=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction__hover_enabled=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction_radial__hover=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_direction_radial__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_start_position__hover=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_start_position__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_end_position__hover=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_end_position__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_overlays_image__hover=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_overlays_image__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_stops__hover=\u00a0\u00bb#2b87da 0%|#29c4a9 100%\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; width=\u00a0\u00bb90%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_px__hover=\u00a0\u00bb1080px\u00a0\u00bb custom_width_px__hover_enabled=\u00a0\u00bb1080px\u00a0\u00bb custom_width_percent__hover=\u00a0\u00bb80%\u00a0\u00bb custom_width_percent__hover_enabled=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb gutter_width__hover=\u00a0\u00bb3&Prime; gutter_width__hover_enabled=\u00a0\u00bb3&Prime; parallax_1__hover=\u00a0\u00bboff\u00a0\u00bb parallax_1__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_2__hover=\u00a0\u00bboff\u00a0\u00bb parallax_2__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_3__hover=\u00a0\u00bboff\u00a0\u00bb parallax_3__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_4__hover=\u00a0\u00bboff\u00a0\u00bb parallax_4__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_5__hover=\u00a0\u00bboff\u00a0\u00bb parallax_5__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_6__hover=\u00a0\u00bboff\u00a0\u00bb parallax_6__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_method_1__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_1__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_2__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_2__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_3__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_3__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_4__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_4__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_5__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_5__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_6__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_6__hover_enabled=\u00a0\u00bbon\u00a0\u00bb use_background_color_gradient__hover=\u00a0\u00bboff\u00a0\u00bb use_background_color_gradient__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_start__hover=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_start__hover_enabled=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_end__hover=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_end__hover_enabled=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_type__hover=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_type__hover_enabled=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_direction__hover=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction__hover_enabled=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction_radial__hover=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_direction_radial__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_start_position__hover=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_start_position__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_end_position__hover=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_end_position__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_overlays_image__hover=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_overlays_image__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax__hover=\u00a0\u00bboff\u00a0\u00bb parallax__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_method__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method__hover_enabled=\u00a0\u00bbon\u00a0\u00bb background_size__hover=\u00a0\u00bbcover\u00a0\u00bb background_size__hover_enabled=\u00a0\u00bbcover\u00a0\u00bb background_position__hover=\u00a0\u00bbcenter\u00a0\u00bb background_position__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_repeat__hover=\u00a0\u00bbno-repeat\u00a0\u00bb background_repeat__hover_enabled=\u00a0\u00bbno-repeat\u00a0\u00bb background_blend__hover=\u00a0\u00bbnormal\u00a0\u00bb background_blend__hover_enabled=\u00a0\u00bbnormal\u00a0\u00bb allow_player_pause__hover=\u00a0\u00bboff\u00a0\u00bb allow_player_pause__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_video_pause_outside_viewport__hover=\u00a0\u00bbon\u00a0\u00bb background_video_pause_outside_viewport__hover_enabled=\u00a0\u00bbon\u00a0\u00bb make_fullwidth__hover=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb width_unit__hover=\u00a0\u00bbon\u00a0\u00bb width_unit__hover_enabled=\u00a0\u00bbon\u00a0\u00bb use_custom_gutter__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_gutter__hover_enabled=\u00a0\u00bboff\u00a0\u00bb make_equal__hover=\u00a0\u00bboff\u00a0\u00bb make_equal__hover_enabled=\u00a0\u00bboff\u00a0\u00bb border_radii__hover=\u00a0\u00bbon||||\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bbon||||\u00a0\u00bb box_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb box_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb box_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb filter_hue_rotate__hover=\u00a0\u00bb0deg\u00a0\u00bb filter_hue_rotate__hover_enabled=\u00a0\u00bb0deg\u00a0\u00bb filter_saturate__hover=\u00a0\u00bb100%\u00a0\u00bb filter_saturate__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_brightness__hover=\u00a0\u00bb100%\u00a0\u00bb filter_brightness__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_contrast__hover=\u00a0\u00bb100%\u00a0\u00bb filter_contrast__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_invert__hover=\u00a0\u00bb0%\u00a0\u00bb filter_invert__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb filter_sepia__hover=\u00a0\u00bb0%\u00a0\u00bb filter_sepia__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb filter_opacity__hover=\u00a0\u00bb100%\u00a0\u00bb filter_opacity__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_blur__hover=\u00a0\u00bb0px\u00a0\u00bb filter_blur__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb mix_blend_mode__hover=\u00a0\u00bbnormal\u00a0\u00bb mix_blend_mode__hover_enabled=\u00a0\u00bbnormal\u00a0\u00bb animation_style__hover=\u00a0\u00bbnone\u00a0\u00bb animation_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb animation_repeat__hover=\u00a0\u00bbonce\u00a0\u00bb animation_repeat__hover_enabled=\u00a0\u00bbonce\u00a0\u00bb animation_direction__hover=\u00a0\u00bbcenter\u00a0\u00bb animation_direction__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb animation_duration__hover=\u00a0\u00bb1000ms\u00a0\u00bb animation_duration__hover_enabled=\u00a0\u00bb1000ms\u00a0\u00bb animation_delay__hover=\u00a0\u00bb0ms\u00a0\u00bb animation_delay__hover_enabled=\u00a0\u00bb0ms\u00a0\u00bb animation_intensity_slide__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_slide__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_zoom__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_zoom__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_flip__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_flip__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_fold__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_fold__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_roll__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_roll__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_starting_opacity__hover=\u00a0\u00bb0%\u00a0\u00bb animation_starting_opacity__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb animation_speed_curve__hover=\u00a0\u00bbease-in-out\u00a0\u00bb animation_speed_curve__hover_enabled=\u00a0\u00bbease-in-out\u00a0\u00bb hover_transition_duration__hover=\u00a0\u00bb300ms\u00a0\u00bb hover_transition_duration__hover_enabled=\u00a0\u00bb300ms\u00a0\u00bb hover_transition_delay__hover=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_delay__hover_enabled=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_speed_curve__hover=\u00a0\u00bbease\u00a0\u00bb hover_transition_speed_curve__hover_enabled=\u00a0\u00bbease\u00a0\u00bb background_color_gradient_stops__hover=\u00a0\u00bb#2b87da 0%|#29c4a9 100%\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font_size=\u00a0\u00bb5em\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb header_5_font=\u00a0\u00bb||||||||\u00a0\u00bb header_6_font=\u00a0\u00bbSource Sans Pro|||on|||||\u00a0\u00bb header_6_font_size=\u00a0\u00bb24px\u00a0\u00bb header_6_letter_spacing=\u00a0\u00bb8px\u00a0\u00bb header_6_line_height=\u00a0\u00bb1.8em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb max_width_tablet=\u00a0\u00bb\u00a0\u00bb max_width_phone=\u00a0\u00bb\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||0px\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_font_size_phone=\u00a0\u00bb48px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_shadow_style=\u00a0\u00bbpreset3&Prime; header_text_shadow_blur_strength=\u00a0\u00bb0.8em\u00a0\u00bb header_text_shadow_color=\u00a0\u00bbrgba(0,17,51,0.55)\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb text_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb text_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb text_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb text_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb text_line_height__hover=\u00a0\u00bb1.7em\u00a0\u00bb text_line_height__hover_enabled=\u00a0\u00bb1.7em\u00a0\u00bb text_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb text_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb text_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb text_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb link_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb link_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb link_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb link_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb link_line_height__hover=\u00a0\u00bb1em\u00a0\u00bb link_line_height__hover_enabled=\u00a0\u00bb1em\u00a0\u00bb link_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb link_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb link_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb link_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb ul_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb ul_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb ul_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb ul_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb ul_line_height__hover=\u00a0\u00bb1em\u00a0\u00bb ul_line_height__hover_enabled=\u00a0\u00bb1em\u00a0\u00bb ul_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb ul_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb ul_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb ul_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb ol_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb ol_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb ol_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb ol_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb ol_line_height__hover=\u00a0\u00bb1em\u00a0\u00bb ol_line_height__hover_enabled=\u00a0\u00bb1em\u00a0\u00bb ol_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb ol_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb ol_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb ol_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb quote_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb quote_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb quote_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb quote_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb quote_line_height__hover=\u00a0\u00bb1em\u00a0\u00bb quote_line_height__hover_enabled=\u00a0\u00bb1em\u00a0\u00bb quote_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb quote_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb quote_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb quote_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb text_orientation__hover=\u00a0\u00bbleft\u00a0\u00bb text_orientation__hover_enabled=\u00a0\u00bbleft\u00a0\u00bb background_layout__hover=\u00a0\u00bblight\u00a0\u00bb background_layout__hover_enabled=\u00a0\u00bblight\u00a0\u00bb]<\/p>\n<h1>Nos activit\u00e9s \u00e0 Gen\u00e8ve<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb7vw\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb24px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.8em\u00a0\u00bb header_5_font=\u00a0\u00bb||||||||\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb max_width=\u00a0\u00bb700px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_font_size_phone=\u00a0\u00bb-3px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb24px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_letter_spacing_tablet=\u00a0\u00bb8px\u00a0\u00bb header_2_letter_spacing_phone=\u00a0\u00bb0px\u00a0\u00bb header_2_letter_spacing_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_shadow_style=\u00a0\u00bbpreset3&Prime; header_text_shadow_blur_strength=\u00a0\u00bb0.8em\u00a0\u00bb header_text_shadow_color=\u00a0\u00bb#001133&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb text_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb text_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb text_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb text_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb text_line_height__hover=\u00a0\u00bb1.7em\u00a0\u00bb text_line_height__hover_enabled=\u00a0\u00bb1.7em\u00a0\u00bb text_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb text_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb text_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb text_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb link_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb link_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb link_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb link_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb link_line_height__hover=\u00a0\u00bb1em\u00a0\u00bb link_line_height__hover_enabled=\u00a0\u00bb1em\u00a0\u00bb link_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb link_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb link_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb link_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb ul_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb ul_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb ul_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb ul_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb ul_line_height__hover=\u00a0\u00bb1em\u00a0\u00bb ul_line_height__hover_enabled=\u00a0\u00bb1em\u00a0\u00bb ul_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb ul_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb ul_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb ul_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb ol_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb ol_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb ol_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb ol_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb ol_line_height__hover=\u00a0\u00bb1em\u00a0\u00bb ol_line_height__hover_enabled=\u00a0\u00bb1em\u00a0\u00bb ol_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb ol_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb ol_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb ol_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb quote_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb quote_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb quote_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb quote_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb quote_line_height__hover=\u00a0\u00bb1em\u00a0\u00bb quote_line_height__hover_enabled=\u00a0\u00bb1em\u00a0\u00bb quote_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb quote_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb quote_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb quote_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb text_orientation__hover=\u00a0\u00bbleft\u00a0\u00bb text_orientation__hover_enabled=\u00a0\u00bbleft\u00a0\u00bb background_layout__hover=\u00a0\u00bblight\u00a0\u00bb background_layout__hover_enabled=\u00a0\u00bblight\u00a0\u00bb header_6_font_size__hover=\u00a0\u00bb14px\u00a0\u00bb header_6_font_size__hover_enabled=\u00a0\u00bb14px\u00a0\u00bb header_6_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb header_6_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb header_6_line_height__hover=\u00a0\u00bb1em\u00a0\u00bb header_6_line_height__hover_enabled=\u00a0\u00bb1em\u00a0\u00bb header_6_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb header_6_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb header_6_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb header_6_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb]<\/p>\n<h2>Le potentiel social des sports de glisse et outdoor<\/h2>\n<p>En offrant un acc\u00e8s aux sports de glisse et outdoor \u00e0 des jeunes en difficult\u00e9, nous offrons plus qu&rsquo;un moment de fun: c&rsquo;est aussi une \u00e9cole de vie<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10vw||10vw||true\u00a0\u00bb overflow-x_tablet=\u00a0\u00bb\u00a0\u00bb overflow-x_phone=\u00a0\u00bb\u00a0\u00bb overflow-x_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_width_px__hover=\u00a0\u00bb1080px\u00a0\u00bb custom_width_px__hover_enabled=\u00a0\u00bb1080px\u00a0\u00bb custom_width_percent__hover=\u00a0\u00bb80%\u00a0\u00bb custom_width_percent__hover_enabled=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb gutter_width__hover=\u00a0\u00bb3&Prime; gutter_width__hover_enabled=\u00a0\u00bb3&Prime; parallax_1__hover=\u00a0\u00bboff\u00a0\u00bb parallax_1__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_2__hover=\u00a0\u00bboff\u00a0\u00bb parallax_2__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_3__hover=\u00a0\u00bboff\u00a0\u00bb parallax_3__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_method_1__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_1__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_2__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_2__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_3__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_3__hover_enabled=\u00a0\u00bbon\u00a0\u00bb use_background_color_gradient__hover=\u00a0\u00bboff\u00a0\u00bb use_background_color_gradient__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_start__hover=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_start__hover_enabled=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_end__hover=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_end__hover_enabled=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_type__hover=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_type__hover_enabled=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_direction__hover=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction__hover_enabled=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction_radial__hover=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_direction_radial__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_start_position__hover=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_start_position__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_end_position__hover=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_end_position__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_overlays_image__hover=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_overlays_image__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax__hover=\u00a0\u00bboff\u00a0\u00bb parallax__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_method__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method__hover_enabled=\u00a0\u00bbon\u00a0\u00bb background_size__hover=\u00a0\u00bbcover\u00a0\u00bb background_size__hover_enabled=\u00a0\u00bbcover\u00a0\u00bb background_position__hover=\u00a0\u00bbcenter\u00a0\u00bb background_position__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_repeat__hover=\u00a0\u00bbno-repeat\u00a0\u00bb background_repeat__hover_enabled=\u00a0\u00bbno-repeat\u00a0\u00bb background_blend__hover=\u00a0\u00bbnormal\u00a0\u00bb background_blend__hover_enabled=\u00a0\u00bbnormal\u00a0\u00bb allow_player_pause__hover=\u00a0\u00bboff\u00a0\u00bb allow_player_pause__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_video_pause_outside_viewport__hover=\u00a0\u00bbon\u00a0\u00bb background_video_pause_outside_viewport__hover_enabled=\u00a0\u00bbon\u00a0\u00bb inner_shadow__hover=\u00a0\u00bboff\u00a0\u00bb inner_shadow__hover_enabled=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb width_unit__hover=\u00a0\u00bbon\u00a0\u00bb width_unit__hover_enabled=\u00a0\u00bbon\u00a0\u00bb make_equal__hover=\u00a0\u00bboff\u00a0\u00bb make_equal__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_gutter__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_gutter__hover_enabled=\u00a0\u00bboff\u00a0\u00bb border_radii__hover=\u00a0\u00bbon||||\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bbon||||\u00a0\u00bb box_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb box_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb box_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb max_width__hover=\u00a0\u00bb100%\u00a0\u00bb max_width__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_hue_rotate__hover=\u00a0\u00bb0deg\u00a0\u00bb filter_hue_rotate__hover_enabled=\u00a0\u00bb0deg\u00a0\u00bb filter_saturate__hover=\u00a0\u00bb100%\u00a0\u00bb filter_saturate__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_brightness__hover=\u00a0\u00bb100%\u00a0\u00bb filter_brightness__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_contrast__hover=\u00a0\u00bb100%\u00a0\u00bb filter_contrast__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_invert__hover=\u00a0\u00bb0%\u00a0\u00bb filter_invert__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb filter_sepia__hover=\u00a0\u00bb0%\u00a0\u00bb filter_sepia__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb filter_opacity__hover=\u00a0\u00bb100%\u00a0\u00bb filter_opacity__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_blur__hover=\u00a0\u00bb0px\u00a0\u00bb filter_blur__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb mix_blend_mode__hover=\u00a0\u00bbnormal\u00a0\u00bb mix_blend_mode__hover_enabled=\u00a0\u00bbnormal\u00a0\u00bb animation_style__hover=\u00a0\u00bbnone\u00a0\u00bb animation_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb animation_repeat__hover=\u00a0\u00bbonce\u00a0\u00bb animation_repeat__hover_enabled=\u00a0\u00bbonce\u00a0\u00bb animation_direction__hover=\u00a0\u00bbcenter\u00a0\u00bb animation_direction__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb animation_duration__hover=\u00a0\u00bb1000ms\u00a0\u00bb animation_duration__hover_enabled=\u00a0\u00bb1000ms\u00a0\u00bb animation_delay__hover=\u00a0\u00bb0ms\u00a0\u00bb animation_delay__hover_enabled=\u00a0\u00bb0ms\u00a0\u00bb animation_intensity_slide__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_slide__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_zoom__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_zoom__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_flip__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_flip__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_fold__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_fold__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_roll__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_roll__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_starting_opacity__hover=\u00a0\u00bb0%\u00a0\u00bb animation_starting_opacity__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb animation_speed_curve__hover=\u00a0\u00bbease-in-out\u00a0\u00bb animation_speed_curve__hover_enabled=\u00a0\u00bbease-in-out\u00a0\u00bb hover_transition_duration__hover=\u00a0\u00bb300ms\u00a0\u00bb hover_transition_duration__hover_enabled=\u00a0\u00bb300ms\u00a0\u00bb hover_transition_delay__hover=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_delay__hover_enabled=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_speed_curve__hover=\u00a0\u00bbease\u00a0\u00bb hover_transition_speed_curve__hover_enabled=\u00a0\u00bbease\u00a0\u00bb background_color_gradient_stops__hover=\u00a0\u00bb#2b87da 0%|#29c4a9 100%\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; animation_style=\u00a0\u00bbfade\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10vw||10vw||true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bbRaleway||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.4em\u00a0\u00bb max_width=\u00a0\u00bb600px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Le skateboard, un brasseur social et une p\u00e9dagogie positive.<\/h2>\n<p>[\/et_pb_text][et_pb_divider divider_weight=\u00a0\u00bb3px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; max_width=\u00a0\u00bb80px\u00a0\u00bb height=\u00a0\u00bb3px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<br \/>\n[\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_5,3_5&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; background_color=\u00a0\u00bbgcid-2475c031-e4fa-4954-ad34-3e39ed2c2109&Prime; width=\u00a0\u00bb90%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb module_alignment=\u00a0\u00bbleft\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|||120px|false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb scroll_horizontal_motion=\u00a0\u00bb0|79|79|100|4|0|-4&Prime; scroll_fade=\u00a0\u00bb0|40|40|100|0|100|100&Prime; border_radii=\u00a0\u00bboff||15px|15px|\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22background_color%22%93}\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bboff|hover\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10vw||10vw||true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb custom_margin=\u00a0\u00bb|20px||20px|false|true\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb14px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<b>Apprendre le skateboard n&rsquo;est pas facile.<\/b>\u00a0Son apprentissage est accompagn\u00e9 de le\u00e7ons de pers\u00e9v\u00e9rance, courage, et r\u00e9silience.<\/p>\n<p>Les skatepark sont des lieux tol\u00e9rants <strong>encourageant l&rsquo;\u00e9change et la rencontre.<\/strong>\u00a0Fr\u00e9quent\u00e9s par toutes les couches sociales, on y \u00e9change \u00a0conseils et astuces entres pratiquants. On y cr\u00e9e de nouveaux liens.<\/p>\n<p>Lors de nos cours,<strong> nous transmettons intentionnellement ces comportements positifs et pro-sociaux gr\u00e2ce \u00e0 des exercices adapt\u00e9s pour tous niveaux.\u00a0<\/strong><\/p>\n<p style=\"text-align: right;\">[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; overflow-x=\u00a0\u00bbvisible\u00a0\u00bb overflow-y=\u00a0\u00bbvisible\u00a0\u00bb custom_padding=\u00a0\u00bb|20px||0px|false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0vw|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2022\/03\/2022.02.21_BAGA_PROJET-ALSF_01286-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbPROJET ASLF &#8211; SKATE\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|on\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; custom_width_px__hover=\u00a0\u00bb1080px\u00a0\u00bb custom_width_px__hover_enabled=\u00a0\u00bb1080px\u00a0\u00bb custom_width_percent__hover=\u00a0\u00bb80%\u00a0\u00bb custom_width_percent__hover_enabled=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb make_fullwidth__hover=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb width_unit__hover=\u00a0\u00bbon\u00a0\u00bb width_unit__hover_enabled=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; background_color=\u00a0\u00bbgcid-2475c031-e4fa-4954-ad34-3e39ed2c2109&Prime; module_alignment=\u00a0\u00bbcenter\u00a0\u00bb min_height=\u00a0\u00bb235px\u00a0\u00bb overflow-x=\u00a0\u00bbvisible\u00a0\u00bb overflow-y=\u00a0\u00bbvisible\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|true\u00a0\u00bb custom_padding=\u00a0\u00bb1em|1em|1em|1em|true|true\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb scroll_fade=\u00a0\u00bb0|40|40|100|0|100|100&Prime; border_radii=\u00a0\u00bbon|2em|2em|2em|2em\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bbRaleway||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.4em\u00a0\u00bb max_width=\u00a0\u00bb600px\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Le skateboard, un brasseur social et une p\u00e9dagogie positive.<\/h2>\n<p>[\/et_pb_text][et_pb_divider divider_weight=\u00a0\u00bb3px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; max_width=\u00a0\u00bb80px\u00a0\u00bb height=\u00a0\u00bb3px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<br \/>\n[\/et_pb_divider][et_pb_image src=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2022\/03\/2022.02.21_BAGA_PROJET-ALSF_01286-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbPROJET ASLF &#8211; SKATE\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb custom_margin=\u00a0\u00bb|20px||20px|false|true\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb14px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><b>Apprendre le skateboard n&rsquo;est pas facile.<\/b>\u00a0Son apprentissage est accompagn\u00e9 de le\u00e7ons de pers\u00e9v\u00e9rance, courage, et r\u00e9silience.<\/p>\n<p>Aussi, <strong>les skatepark sont des lieux tol\u00e9rants encourageant l&rsquo;\u00e9change et la rencontre.<\/strong>\u00a0Fr\u00e9quent\u00e9s par toutes les couches sociales, on y \u00e9change \u00a0conseils et astuces entres pratiquants. On y cr\u00e9e de nouveaux liens.<\/p>\n<p>Lors de nos cours,<strong> nous transmettons intentionnellement ces comportements positifs et pro-sociaux gr\u00e2ce \u00e0 des exercices adapt\u00e9s pour tous niveaux.\u00a0<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb15px||0px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbbounce\u00a0\u00bb animation_duration=\u00a0\u00bb1500ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][ba_video_popup image=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2026\/04\/screenshot_video_cours_skate.png\u00a0\u00bb icon=\u00a0\u00bb6&Prime; video_link=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=POdIsAhQSeM\u00a0\u00bb img_height=\u00a0\u00bb150px\u00a0\u00bb icon_color=\u00a0\u00bbgcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155&Prime; icon_size=\u00a0\u00bb30px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb trigger_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb trigger_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb width=\u00a0\u00bb300px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin-bottom: 6% !important;\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.2)\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22text_box_bg%22%93,%22gcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155%22:%91%22icon_color%22%93}\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb][\/ba_video_popup][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Vid\u00e9o cours de skate<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][ba_video_popup image=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2026\/04\/screenshot_video_out_of_town.png\u00a0\u00bb icon=\u00a0\u00bb6&Prime; video_link=\u00a0\u00bbhttps:\/\/youtu.be\/REmRCbGN_rM\u00a0\u00bb img_height=\u00a0\u00bb150px\u00a0\u00bb icon_color=\u00a0\u00bbgcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155&Prime; icon_size=\u00a0\u00bb30px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb trigger_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb trigger_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb width=\u00a0\u00bb300px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin-bottom: 6% !important;\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.2)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22text_box_bg%22%93,%22gcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155%22:%91%22icon_color%22%93}\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb][\/ba_video_popup][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Vid\u00e9o Out of town<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][ba_video_popup image=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2026\/04\/screenshot_video_camp_skate.png\u00a0\u00bb icon=\u00a0\u00bb6&Prime; video_link=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=WbrX5JrwXlM\u00a0\u00bb img_height=\u00a0\u00bb150px\u00a0\u00bb icon_color=\u00a0\u00bbgcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155&Prime; icon_size=\u00a0\u00bb30px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb trigger_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb trigger_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb width=\u00a0\u00bb300px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin-bottom: 6% !important;\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.2)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22text_box_bg%22%93,%22gcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155%22:%91%22icon_color%22%93}\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb][\/ba_video_popup][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Vid\u00e9o camp de skate<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bboff|tablet\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10vw||10vw||true\u00a0\u00bb custom_width_px__hover=\u00a0\u00bb1080px\u00a0\u00bb custom_width_px__hover_enabled=\u00a0\u00bb1080px\u00a0\u00bb custom_width_percent__hover=\u00a0\u00bb80%\u00a0\u00bb custom_width_percent__hover_enabled=\u00a0\u00bb80%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb gutter_width__hover=\u00a0\u00bb3&Prime; gutter_width__hover_enabled=\u00a0\u00bb3&Prime; parallax_1__hover=\u00a0\u00bboff\u00a0\u00bb parallax_1__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_2__hover=\u00a0\u00bboff\u00a0\u00bb parallax_2__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_3__hover=\u00a0\u00bboff\u00a0\u00bb parallax_3__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_method_1__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_1__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_2__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_2__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_3__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_3__hover_enabled=\u00a0\u00bbon\u00a0\u00bb use_background_color_gradient__hover=\u00a0\u00bboff\u00a0\u00bb use_background_color_gradient__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_start__hover=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_start__hover_enabled=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_end__hover=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_end__hover_enabled=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_type__hover=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_type__hover_enabled=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_direction__hover=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction__hover_enabled=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction_radial__hover=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_direction_radial__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_start_position__hover=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_start_position__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_end_position__hover=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_end_position__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_overlays_image__hover=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_overlays_image__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax__hover=\u00a0\u00bboff\u00a0\u00bb parallax__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_method__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method__hover_enabled=\u00a0\u00bbon\u00a0\u00bb background_size__hover=\u00a0\u00bbcover\u00a0\u00bb background_size__hover_enabled=\u00a0\u00bbcover\u00a0\u00bb background_position__hover=\u00a0\u00bbcenter\u00a0\u00bb background_position__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_repeat__hover=\u00a0\u00bbno-repeat\u00a0\u00bb background_repeat__hover_enabled=\u00a0\u00bbno-repeat\u00a0\u00bb background_blend__hover=\u00a0\u00bbnormal\u00a0\u00bb background_blend__hover_enabled=\u00a0\u00bbnormal\u00a0\u00bb allow_player_pause__hover=\u00a0\u00bboff\u00a0\u00bb allow_player_pause__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_video_pause_outside_viewport__hover=\u00a0\u00bbon\u00a0\u00bb background_video_pause_outside_viewport__hover_enabled=\u00a0\u00bbon\u00a0\u00bb inner_shadow__hover=\u00a0\u00bboff\u00a0\u00bb inner_shadow__hover_enabled=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb width_unit__hover=\u00a0\u00bbon\u00a0\u00bb width_unit__hover_enabled=\u00a0\u00bbon\u00a0\u00bb make_equal__hover=\u00a0\u00bboff\u00a0\u00bb make_equal__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_gutter__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_gutter__hover_enabled=\u00a0\u00bboff\u00a0\u00bb border_radii__hover=\u00a0\u00bbon||||\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bbon||||\u00a0\u00bb box_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb box_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb box_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb max_width__hover=\u00a0\u00bb100%\u00a0\u00bb max_width__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_hue_rotate__hover=\u00a0\u00bb0deg\u00a0\u00bb filter_hue_rotate__hover_enabled=\u00a0\u00bb0deg\u00a0\u00bb filter_saturate__hover=\u00a0\u00bb100%\u00a0\u00bb filter_saturate__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_brightness__hover=\u00a0\u00bb100%\u00a0\u00bb filter_brightness__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_contrast__hover=\u00a0\u00bb100%\u00a0\u00bb filter_contrast__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_invert__hover=\u00a0\u00bb0%\u00a0\u00bb filter_invert__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb filter_sepia__hover=\u00a0\u00bb0%\u00a0\u00bb filter_sepia__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb filter_opacity__hover=\u00a0\u00bb100%\u00a0\u00bb filter_opacity__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_blur__hover=\u00a0\u00bb0px\u00a0\u00bb filter_blur__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb mix_blend_mode__hover=\u00a0\u00bbnormal\u00a0\u00bb mix_blend_mode__hover_enabled=\u00a0\u00bbnormal\u00a0\u00bb animation_style__hover=\u00a0\u00bbnone\u00a0\u00bb animation_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb animation_repeat__hover=\u00a0\u00bbonce\u00a0\u00bb animation_repeat__hover_enabled=\u00a0\u00bbonce\u00a0\u00bb animation_direction__hover=\u00a0\u00bbcenter\u00a0\u00bb animation_direction__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb animation_duration__hover=\u00a0\u00bb1000ms\u00a0\u00bb animation_duration__hover_enabled=\u00a0\u00bb1000ms\u00a0\u00bb animation_delay__hover=\u00a0\u00bb0ms\u00a0\u00bb animation_delay__hover_enabled=\u00a0\u00bb0ms\u00a0\u00bb animation_intensity_slide__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_slide__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_zoom__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_zoom__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_flip__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_flip__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_fold__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_fold__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_roll__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_roll__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_starting_opacity__hover=\u00a0\u00bb0%\u00a0\u00bb animation_starting_opacity__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb animation_speed_curve__hover=\u00a0\u00bbease-in-out\u00a0\u00bb animation_speed_curve__hover_enabled=\u00a0\u00bbease-in-out\u00a0\u00bb hover_transition_duration__hover=\u00a0\u00bb300ms\u00a0\u00bb hover_transition_duration__hover_enabled=\u00a0\u00bb300ms\u00a0\u00bb hover_transition_delay__hover=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_delay__hover_enabled=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_speed_curve__hover=\u00a0\u00bbease\u00a0\u00bb hover_transition_speed_curve__hover_enabled=\u00a0\u00bbease\u00a0\u00bb background_color_gradient_stops__hover=\u00a0\u00bb#2b87da 0%|#29c4a9 100%\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; animation_style=\u00a0\u00bbfade\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10vw||10vw||true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; text_font=\u00a0\u00bbRaleway||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.4em\u00a0\u00bb text_orientation=\u00a0\u00bbright\u00a0\u00bb max_width=\u00a0\u00bb600px\u00a0\u00bb module_alignment=\u00a0\u00bbright\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Ski et Snowboard, rencontrer la Suisse et sa nature<\/h2>\n<p>[\/et_pb_text][et_pb_divider divider_weight=\u00a0\u00bb3px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; max_width=\u00a0\u00bb80px\u00a0\u00bb module_alignment=\u00a0\u00bbright\u00a0\u00bb height=\u00a0\u00bb3px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<br \/>\n[\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb3_5,2_5&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; background_color=\u00a0\u00bbgcid-2475c031-e4fa-4954-ad34-3e39ed2c2109&Prime; width=\u00a0\u00bb90%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb module_alignment=\u00a0\u00bbright\u00a0\u00bb custom_padding=\u00a0\u00bb|120px|||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbright\u00a0\u00bb scroll_fade=\u00a0\u00bb0|40|40|100|0|100|100&Prime; border_radii=\u00a0\u00bboff|15px|||15px\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|||20px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2022\/03\/2022.03.05_BAGA_PROJET-ALSF_01578-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbPROJET ASLF &#8211; SKI\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10vw||10vw||true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb custom_margin=\u00a0\u00bb|20px||20px|false|true\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb14px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Nos initiations au ski et snowboard renforcent le sentiment d&rsquo;appartenance et la sant\u00e9 mentale.<\/strong> Ils sont l&rsquo;occasion pour nos participant de prendre le grand air. L\u00e0-haut, ils d\u00e9couvrent la Suisse, ses montagnes enneig\u00e9s et sa culture au-del\u00e0 du milieu urbain.<\/p>\n<p><strong>Nous profitons \u00e9galement de ce moment dans la nature pour sensibiliser \u00e0 la protection de l&rsquo;environnement<\/strong>. Nous partageons notre savoir sur le milieu montagneux et promouvons les gestes \u00e9co-responsables<\/p>\n<p>A travers nos cours, nous encourageons l&rsquo;int\u00e9gration de jeunes et sensibilisons \u00e0 la protection de la nature.<\/p>\n<p>[\/et_pb_text][ba_video_popup image=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2026\/02\/camp-hiver-1-scaled.jpeg\u00a0\u00bb icon=\u00a0\u00bb6&Prime; video_link=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=0mq2nltRroc\u00a0\u00bb img_height=\u00a0\u00bb150px\u00a0\u00bb icon_color=\u00a0\u00bbgcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155&Prime; icon_size=\u00a0\u00bb30px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb trigger_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb trigger_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb width=\u00a0\u00bb300px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin-bottom: 6% !important;\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.2)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22text_box_bg%22%93,%22gcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155%22:%91%22icon_color%22%93}\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb][\/ba_video_popup][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Vid\u00e9o camp d&rsquo;hiver<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|on\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; custom_width_px__hover=\u00a0\u00bb1080px\u00a0\u00bb custom_width_px__hover_enabled=\u00a0\u00bb1080px\u00a0\u00bb custom_width_percent__hover=\u00a0\u00bb80%\u00a0\u00bb custom_width_percent__hover_enabled=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb make_fullwidth__hover=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb width_unit__hover=\u00a0\u00bbon\u00a0\u00bb width_unit__hover_enabled=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; background_color=\u00a0\u00bbgcid-2475c031-e4fa-4954-ad34-3e39ed2c2109&Prime; module_alignment=\u00a0\u00bbcenter\u00a0\u00bb min_height=\u00a0\u00bb261px\u00a0\u00bb overflow-x=\u00a0\u00bbvisible\u00a0\u00bb overflow-y=\u00a0\u00bbvisible\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|true\u00a0\u00bb custom_padding=\u00a0\u00bb1em|1em|1em|1em|true|true\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb scroll_fade=\u00a0\u00bb0|40|40|100|0|100|100&Prime; border_radii=\u00a0\u00bbon|2em|2em|2em|2em\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; text_font=\u00a0\u00bbRaleway||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.4em\u00a0\u00bb max_width=\u00a0\u00bb600px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Ski et Snowboard, rencontrer la Suisse et sa nature<\/h2>\n<p>[\/et_pb_text][et_pb_divider divider_weight=\u00a0\u00bb3px\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; max_width=\u00a0\u00bb80px\u00a0\u00bb height=\u00a0\u00bb3px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<br \/>\n[\/et_pb_divider][et_pb_image src=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2022\/03\/2022.03.05_BAGA_PROJET-ALSF_01578-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbPROJET ASLF &#8211; SKI\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb custom_margin=\u00a0\u00bb|20px||20px|false|true\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb14px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Nos initiations au ski et snowboard renforcent le sentiment d&rsquo;appartenance et la sant\u00e9 mentale.<\/strong> Ils sont l&rsquo;occasion pour nos participant de prendre le grand air. L\u00e0-haut, ils d\u00e9couvrent la Suisse, ses montagnes enneig\u00e9s et sa culture au-del\u00e0 du milieu urbain.<\/p>\n<p><strong>Nous profitons \u00e9galement de ce moment dans la nature pour sensibiliser \u00e0 la protection de l&rsquo;environnement<\/strong>. Nous partageons notre savoir sur le milieu montagneux et promouvons les gestes \u00e9co-responsables<\/p>\n<p>A travers nos cours, nous encourageons l&rsquo;int\u00e9gration de jeunes et sensibilisons \u00e0 la protection de la nature.<\/p>\n<p>[\/et_pb_text][ba_video_popup use_overlay=\u00a0\u00bboff\u00a0\u00bb trigger_element=\u00a0\u00bbtext\u00a0\u00bb text=\u00a0\u00bbVoir la vid\u00e9o ski et snowboard\u00a0\u00bb video_link=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=0mq2nltRroc\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb trigger_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb trigger_text_color=\u00a0\u00bbgcid-heading-color\u00a0\u00bb trigger_font_size=\u00a0\u00bb20px\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb max_width=\u00a0\u00bb280px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb10px||10px||false|false\u00a0\u00bb border_radii=\u00a0\u00bbon|5px|5px|5px|5px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.2)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-body-color%22:%91%22icon_color%22%93,%22gcid-heading-color%22:%91%22trigger_text_color%22%93}\u00a0\u00bb transform_styles__hover_enabled=\u00a0\u00bboff|hover\u00a0\u00bb transform_scale__hover_enabled=\u00a0\u00bboff|hover\u00a0\u00bb transform_translate__hover_enabled=\u00a0\u00bboff|hover\u00a0\u00bb transform_rotate__hover_enabled=\u00a0\u00bboff|hover\u00a0\u00bb transform_skew__hover_enabled=\u00a0\u00bboff|hover\u00a0\u00bb transform_origin__hover_enabled=\u00a0\u00bboff|hover\u00a0\u00bb][\/ba_video_popup][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb||||false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10vw||10vw||true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb custom_width_px__hover=\u00a0\u00bb1080px\u00a0\u00bb custom_width_px__hover_enabled=\u00a0\u00bb1080px\u00a0\u00bb custom_width_percent__hover=\u00a0\u00bb80%\u00a0\u00bb custom_width_percent__hover_enabled=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb gutter_width__hover=\u00a0\u00bb3&Prime; gutter_width__hover_enabled=\u00a0\u00bb3&Prime; parallax_1__hover=\u00a0\u00bboff\u00a0\u00bb parallax_1__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_2__hover=\u00a0\u00bboff\u00a0\u00bb parallax_2__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_3__hover=\u00a0\u00bboff\u00a0\u00bb parallax_3__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_method_1__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_1__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_2__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_2__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_3__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_3__hover_enabled=\u00a0\u00bbon\u00a0\u00bb use_background_color_gradient__hover=\u00a0\u00bboff\u00a0\u00bb use_background_color_gradient__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_start__hover=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_start__hover_enabled=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_end__hover=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_end__hover_enabled=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_type__hover=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_type__hover_enabled=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_direction__hover=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction__hover_enabled=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction_radial__hover=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_direction_radial__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_start_position__hover=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_start_position__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_end_position__hover=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_end_position__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_overlays_image__hover=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_overlays_image__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax__hover=\u00a0\u00bboff\u00a0\u00bb parallax__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_method__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method__hover_enabled=\u00a0\u00bbon\u00a0\u00bb background_size__hover=\u00a0\u00bbcover\u00a0\u00bb background_size__hover_enabled=\u00a0\u00bbcover\u00a0\u00bb background_position__hover=\u00a0\u00bbcenter\u00a0\u00bb background_position__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_repeat__hover=\u00a0\u00bbno-repeat\u00a0\u00bb background_repeat__hover_enabled=\u00a0\u00bbno-repeat\u00a0\u00bb background_blend__hover=\u00a0\u00bbnormal\u00a0\u00bb background_blend__hover_enabled=\u00a0\u00bbnormal\u00a0\u00bb allow_player_pause__hover=\u00a0\u00bboff\u00a0\u00bb allow_player_pause__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_video_pause_outside_viewport__hover=\u00a0\u00bbon\u00a0\u00bb background_video_pause_outside_viewport__hover_enabled=\u00a0\u00bbon\u00a0\u00bb inner_shadow__hover=\u00a0\u00bboff\u00a0\u00bb inner_shadow__hover_enabled=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb width_unit__hover=\u00a0\u00bbon\u00a0\u00bb width_unit__hover_enabled=\u00a0\u00bbon\u00a0\u00bb make_equal__hover=\u00a0\u00bboff\u00a0\u00bb make_equal__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_gutter__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_gutter__hover_enabled=\u00a0\u00bboff\u00a0\u00bb border_radii__hover=\u00a0\u00bbon||||\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bbon||||\u00a0\u00bb box_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb box_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb box_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb max_width__hover=\u00a0\u00bb100%\u00a0\u00bb max_width__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_hue_rotate__hover=\u00a0\u00bb0deg\u00a0\u00bb filter_hue_rotate__hover_enabled=\u00a0\u00bb0deg\u00a0\u00bb filter_saturate__hover=\u00a0\u00bb100%\u00a0\u00bb filter_saturate__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_brightness__hover=\u00a0\u00bb100%\u00a0\u00bb filter_brightness__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_contrast__hover=\u00a0\u00bb100%\u00a0\u00bb filter_contrast__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_invert__hover=\u00a0\u00bb0%\u00a0\u00bb filter_invert__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb filter_sepia__hover=\u00a0\u00bb0%\u00a0\u00bb filter_sepia__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb filter_opacity__hover=\u00a0\u00bb100%\u00a0\u00bb filter_opacity__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_blur__hover=\u00a0\u00bb0px\u00a0\u00bb filter_blur__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb mix_blend_mode__hover=\u00a0\u00bbnormal\u00a0\u00bb mix_blend_mode__hover_enabled=\u00a0\u00bbnormal\u00a0\u00bb animation_style__hover=\u00a0\u00bbnone\u00a0\u00bb animation_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb animation_repeat__hover=\u00a0\u00bbonce\u00a0\u00bb animation_repeat__hover_enabled=\u00a0\u00bbonce\u00a0\u00bb animation_direction__hover=\u00a0\u00bbcenter\u00a0\u00bb animation_direction__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb animation_duration__hover=\u00a0\u00bb1000ms\u00a0\u00bb animation_duration__hover_enabled=\u00a0\u00bb1000ms\u00a0\u00bb animation_delay__hover=\u00a0\u00bb0ms\u00a0\u00bb animation_delay__hover_enabled=\u00a0\u00bb0ms\u00a0\u00bb animation_intensity_slide__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_slide__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_zoom__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_zoom__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_flip__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_flip__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_fold__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_fold__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_roll__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_roll__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_starting_opacity__hover=\u00a0\u00bb0%\u00a0\u00bb animation_starting_opacity__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb animation_speed_curve__hover=\u00a0\u00bbease-in-out\u00a0\u00bb animation_speed_curve__hover_enabled=\u00a0\u00bbease-in-out\u00a0\u00bb hover_transition_duration__hover=\u00a0\u00bb300ms\u00a0\u00bb hover_transition_duration__hover_enabled=\u00a0\u00bb300ms\u00a0\u00bb hover_transition_delay__hover=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_delay__hover_enabled=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_speed_curve__hover=\u00a0\u00bbease\u00a0\u00bb hover_transition_speed_curve__hover_enabled=\u00a0\u00bbease\u00a0\u00bb background_color_gradient_stops__hover=\u00a0\u00bb#2b87da 0%|#29c4a9 100%\u00a0\u00bb][et_pb_row module_id=\u00a0\u00bbTrampoline\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; animation_style=\u00a0\u00bbfade\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10vw||10vw||true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; text_font=\u00a0\u00bbRaleway||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.4em\u00a0\u00bb max_width=\u00a0\u00bb600px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>L&rsquo;escalade, pour une meilleur conscience de soi<\/h2>\n<p>[\/et_pb_text][et_pb_divider divider_weight=\u00a0\u00bb3px\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; max_width=\u00a0\u00bb80px\u00a0\u00bb height=\u00a0\u00bb3px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<br \/>\n[\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_5,3_5&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; background_color=\u00a0\u00bbgcid-2475c031-e4fa-4954-ad34-3e39ed2c2109&Prime; width=\u00a0\u00bb90%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb module_alignment=\u00a0\u00bbleft\u00a0\u00bb overflow-x=\u00a0\u00bbvisible\u00a0\u00bb overflow-y=\u00a0\u00bbvisible\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|||120px|false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb scroll_fade=\u00a0\u00bb0|40|40|100|0|100|100&Prime; border_radii=\u00a0\u00bboff||15px|15px|\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22background_color%22,%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10vw||10vw||true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb custom_margin=\u00a0\u00bb|20px||20px|false|true\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb14px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>L&rsquo;escalade permet de <b>prendre de la hauteur et d\u00e9velopper la gestion de l&rsquo;\u00e9quilibre en mouvement<\/b>. Ainsi, les jeunes prennent conscience de leur\u00a0corps dans l&rsquo;espace.<\/p>\n<p>Tout comme les skateparks, les salles de grimpes sont des lieux de rencontres. On y rencontre<b> la communaut\u00e9 de grimpe,<\/b> connu pour \u00eatre<b> accueillante et ouverte d&rsquo;esprit. \u00a0 \u00a0<\/b><\/p>\n<p>Tous les cours de grimpe sont accompagn\u00e9 d&rsquo;une s\u00e9ance de <strong>r<\/strong><b>enforcement musculaire et d&rsquo;assouplissement <\/b>afin de pr\u00e9venir les blessures.<\/p>\n<p>Gr\u00e2ce aux cours de grimpe, les jeunes renforcent leurs corps et esprits, rencontrent de nouvelles personnes et d\u00e9cuple leurs progr\u00e8s dans les autres sports!<\/p>\n<p>[\/et_pb_text][ba_video_popup image=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2026\/03\/Capture-decran-2026-03-10-094924.png\u00a0\u00bb icon=\u00a0\u00bb6&Prime; video_link=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=ZY_W0FyH3cE\u00a0\u00bb img_height=\u00a0\u00bb150px\u00a0\u00bb icon_color=\u00a0\u00bbgcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155&Prime; icon_size=\u00a0\u00bb30px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb trigger_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb trigger_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb width=\u00a0\u00bb300px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin-bottom: 6% !important;\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.2)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22text_box_bg%22%93,%22gcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155%22:%91%22icon_color%22%93}\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb][\/ba_video_popup][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Vid\u00e9o grimpe<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; overflow-x=\u00a0\u00bbvisible\u00a0\u00bb overflow-y=\u00a0\u00bbvisible\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0vw|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-24-at-21.51.25.jpeg\u00a0\u00bb title_text=\u00a0\u00bbWhatsApp Image 2024-01-24 at 21.51.25&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|on\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; custom_padding=\u00a0\u00bb|0px||0px|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10vw||10vw||true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb overflow-x_tablet=\u00a0\u00bb\u00a0\u00bb overflow-x_phone=\u00a0\u00bb\u00a0\u00bb overflow-x_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb overflow-y_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb custom_width_px__hover=\u00a0\u00bb1080px\u00a0\u00bb custom_width_px__hover_enabled=\u00a0\u00bb1080px\u00a0\u00bb custom_width_percent__hover=\u00a0\u00bb80%\u00a0\u00bb custom_width_percent__hover_enabled=\u00a0\u00bb80%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb gutter_width__hover=\u00a0\u00bb3&Prime; gutter_width__hover_enabled=\u00a0\u00bb3&Prime; parallax_1__hover=\u00a0\u00bboff\u00a0\u00bb parallax_1__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_2__hover=\u00a0\u00bboff\u00a0\u00bb parallax_2__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_3__hover=\u00a0\u00bboff\u00a0\u00bb parallax_3__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_method_1__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_1__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_2__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_2__hover_enabled=\u00a0\u00bbon\u00a0\u00bb parallax_method_3__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method_3__hover_enabled=\u00a0\u00bbon\u00a0\u00bb use_background_color_gradient__hover=\u00a0\u00bboff\u00a0\u00bb use_background_color_gradient__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_start__hover=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_start__hover_enabled=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_end__hover=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_end__hover_enabled=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_type__hover=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_type__hover_enabled=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_direction__hover=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction__hover_enabled=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction_radial__hover=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_direction_radial__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_start_position__hover=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_start_position__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_end_position__hover=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_end_position__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_overlays_image__hover=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_overlays_image__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax__hover=\u00a0\u00bboff\u00a0\u00bb parallax__hover_enabled=\u00a0\u00bboff\u00a0\u00bb parallax_method__hover=\u00a0\u00bbon\u00a0\u00bb parallax_method__hover_enabled=\u00a0\u00bbon\u00a0\u00bb background_size__hover=\u00a0\u00bbcover\u00a0\u00bb background_size__hover_enabled=\u00a0\u00bbcover\u00a0\u00bb background_position__hover=\u00a0\u00bbcenter\u00a0\u00bb background_position__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_repeat__hover=\u00a0\u00bbno-repeat\u00a0\u00bb background_repeat__hover_enabled=\u00a0\u00bbno-repeat\u00a0\u00bb background_blend__hover=\u00a0\u00bbnormal\u00a0\u00bb background_blend__hover_enabled=\u00a0\u00bbnormal\u00a0\u00bb allow_player_pause__hover=\u00a0\u00bboff\u00a0\u00bb allow_player_pause__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_video_pause_outside_viewport__hover=\u00a0\u00bbon\u00a0\u00bb background_video_pause_outside_viewport__hover_enabled=\u00a0\u00bbon\u00a0\u00bb inner_shadow__hover=\u00a0\u00bboff\u00a0\u00bb inner_shadow__hover_enabled=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover=\u00a0\u00bboff\u00a0\u00bb make_fullwidth__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb width_unit__hover=\u00a0\u00bbon\u00a0\u00bb width_unit__hover_enabled=\u00a0\u00bbon\u00a0\u00bb make_equal__hover=\u00a0\u00bboff\u00a0\u00bb make_equal__hover_enabled=\u00a0\u00bboff\u00a0\u00bb use_custom_gutter__hover=\u00a0\u00bboff\u00a0\u00bb use_custom_gutter__hover_enabled=\u00a0\u00bboff\u00a0\u00bb border_radii__hover=\u00a0\u00bbon||||\u00a0\u00bb border_radii__hover_enabled=\u00a0\u00bbon||||\u00a0\u00bb box_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb box_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb box_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb max_width__hover=\u00a0\u00bb100%\u00a0\u00bb max_width__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_hue_rotate__hover=\u00a0\u00bb0deg\u00a0\u00bb filter_hue_rotate__hover_enabled=\u00a0\u00bb0deg\u00a0\u00bb filter_saturate__hover=\u00a0\u00bb100%\u00a0\u00bb filter_saturate__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_brightness__hover=\u00a0\u00bb100%\u00a0\u00bb filter_brightness__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_contrast__hover=\u00a0\u00bb100%\u00a0\u00bb filter_contrast__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_invert__hover=\u00a0\u00bb0%\u00a0\u00bb filter_invert__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb filter_sepia__hover=\u00a0\u00bb0%\u00a0\u00bb filter_sepia__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb filter_opacity__hover=\u00a0\u00bb100%\u00a0\u00bb filter_opacity__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb filter_blur__hover=\u00a0\u00bb0px\u00a0\u00bb filter_blur__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb mix_blend_mode__hover=\u00a0\u00bbnormal\u00a0\u00bb mix_blend_mode__hover_enabled=\u00a0\u00bbnormal\u00a0\u00bb animation_style__hover=\u00a0\u00bbnone\u00a0\u00bb animation_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb animation_repeat__hover=\u00a0\u00bbonce\u00a0\u00bb animation_repeat__hover_enabled=\u00a0\u00bbonce\u00a0\u00bb animation_direction__hover=\u00a0\u00bbcenter\u00a0\u00bb animation_direction__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb animation_duration__hover=\u00a0\u00bb1000ms\u00a0\u00bb animation_duration__hover_enabled=\u00a0\u00bb1000ms\u00a0\u00bb animation_delay__hover=\u00a0\u00bb0ms\u00a0\u00bb animation_delay__hover_enabled=\u00a0\u00bb0ms\u00a0\u00bb animation_intensity_slide__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_slide__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_zoom__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_zoom__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_flip__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_flip__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_fold__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_fold__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_roll__hover=\u00a0\u00bb50%\u00a0\u00bb animation_intensity_roll__hover_enabled=\u00a0\u00bb50%\u00a0\u00bb animation_starting_opacity__hover=\u00a0\u00bb0%\u00a0\u00bb animation_starting_opacity__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb animation_speed_curve__hover=\u00a0\u00bbease-in-out\u00a0\u00bb animation_speed_curve__hover_enabled=\u00a0\u00bbease-in-out\u00a0\u00bb hover_transition_duration__hover=\u00a0\u00bb300ms\u00a0\u00bb hover_transition_duration__hover_enabled=\u00a0\u00bb300ms\u00a0\u00bb hover_transition_delay__hover=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_delay__hover_enabled=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_speed_curve__hover=\u00a0\u00bbease\u00a0\u00bb hover_transition_speed_curve__hover_enabled=\u00a0\u00bbease\u00a0\u00bb background_color_gradient_stops__hover=\u00a0\u00bb#2b87da 0%|#29c4a9 100%\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; background_color=\u00a0\u00bbgcid-2475c031-e4fa-4954-ad34-3e39ed2c2109&Prime; width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb module_alignment=\u00a0\u00bbleft\u00a0\u00bb min_height=\u00a0\u00bb261px\u00a0\u00bb overflow-x=\u00a0\u00bbvisible\u00a0\u00bb overflow-y=\u00a0\u00bbvisible\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|true\u00a0\u00bb custom_padding=\u00a0\u00bb1em|1em|1em|1em|true|true\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb scroll_fade=\u00a0\u00bb0|40|40|100|0|100|100&Prime; border_radii=\u00a0\u00bbon|2em|2em|2em|2em\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-2475c031-e4fa-4954-ad34-3e39ed2c2109%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; text_font=\u00a0\u00bbRaleway||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.4em\u00a0\u00bb max_width=\u00a0\u00bb600px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>L&rsquo;escalade, pour une meilleure conscience de soi<\/h2>\n<p>[\/et_pb_text][et_pb_divider divider_weight=\u00a0\u00bb3px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; max_width=\u00a0\u00bb80px\u00a0\u00bb height=\u00a0\u00bb3px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<br \/>\n[\/et_pb_divider][et_pb_image src=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-01-24-at-21.51.25.jpeg\u00a0\u00bb title_text=\u00a0\u00bbWhatsApp Image 2024-01-24 at 21.51.25&Prime; src_tablet=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2023\/03\/20220520_180549-scaled.jpg\u00a0\u00bb src_phone=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2023\/03\/20220520_180549-scaled.jpg\u00a0\u00bb src_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb custom_margin=\u00a0\u00bb|20px||20px|false|true\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb14px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>L&rsquo;escalade permet de <b>prendre de la hauteur et d\u00e9velopper la gestion de l&rsquo;\u00e9quilibre en mouvement<\/b>. Ainsi, les jeunes prennent conscience de leur\u00a0corps dans l&rsquo;espace.<\/p>\n<p>Tout comme les skateparks, les salles de grimpes sont des lieux de rencontres. On y rencontre<b> la communaut\u00e9 de grimpe,<\/b> connu pour \u00eatre<b> accueillante et ouverte d&rsquo;esprit. \u00a0 \u00a0<\/b><\/p>\n<p>Tous les cours de grimpe sont accompagn\u00e9 d&rsquo;une s\u00e9ance de r<b>enforcement musculaire et d&rsquo;assouplissement <\/b>afin de pr\u00e9venir les blessures.<\/p>\n<p>Gr\u00e2ce aux cours de grimpe, les jeunes renforcent leurs corps et esprits, rencontrent de nouvelles personnes et d\u00e9cuple leurs progr\u00e8s dans les autres sports!<\/p>\n<p style=\"text-align: left;\">[\/et_pb_text][ba_video_popup use_overlay=\u00a0\u00bboff\u00a0\u00bb trigger_element=\u00a0\u00bbtext\u00a0\u00bb text=\u00a0\u00bbVoir la vid\u00e9o grimpe\u00a0\u00bb video_link=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=ZY_W0FyH3cE\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb trigger_font=\u00a0\u00bb&#8211;et_global_heading_font||||||||\u00a0\u00bb trigger_text_color=\u00a0\u00bbgcid-heading-color\u00a0\u00bb trigger_font_size=\u00a0\u00bb20px\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb max_width=\u00a0\u00bb280px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb10px||10px||false|false\u00a0\u00bb border_radii=\u00a0\u00bbon|5px|5px|5px|5px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.2)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-body-color%22:%91%22icon_color%22%93,%22gcid-heading-color%22:%91%22trigger_text_color%22%93}\u00a0\u00bb transform_styles__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb transform_scale__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb transform_translate__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb transform_rotate__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb transform_skew__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb transform_origin__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb transform_scale__hover=\u00a0\u00bb120%|120%\u00a0\u00bb][\/ba_video_popup][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbDonation\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(165,206,199,0.15) 50%|#151f33 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bbrgba(165,206,199,0.15)\u00a0\u00bb background_color_gradient_start_position=\u00a0\u00bb50%\u00a0\u00bb background_color_gradient_end=\u00a0\u00bb#151f33&Prime; background_image=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2022\/03\/2022.03.05_BAGA_PROJET-ALSF_00467-scaled.jpg\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb10%\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset6&Prime; box_shadow_vertical=\u00a0\u00bb240px\u00a0\u00bb box_shadow_blur=\u00a0\u00bb120px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb-80px\u00a0\u00bb box_shadow_color=\u00a0\u00bb#ffffff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb background_color_gradient_start__hover=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_start__hover_enabled=\u00a0\u00bb#2b87da\u00a0\u00bb background_color_gradient_end__hover=\u00a0\u00bb#29c4a9&Prime; background_color_gradient_end__hover_enabled=\u00a0\u00bb#29c4a9&Prime; use_background_color_gradient__hover=\u00a0\u00bboff\u00a0\u00bb use_background_color_gradient__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_type__hover=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_type__hover_enabled=\u00a0\u00bblinear\u00a0\u00bb background_color_gradient_direction__hover=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction__hover_enabled=\u00a0\u00bb180deg\u00a0\u00bb background_color_gradient_direction_radial__hover=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_direction_radial__hover_enabled=\u00a0\u00bbcenter\u00a0\u00bb background_color_gradient_start_position__hover=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_start_position__hover_enabled=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_end_position__hover=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_end_position__hover_enabled=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_overlays_image__hover=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_overlays_image__hover_enabled=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_stops__hover=\u00a0\u00bb#2b87da 0%|#29c4a9 100%\u00a0\u00bb][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_image=\u00a0\u00bbhttps:\/\/rookieslash.org\/wp-content\/uploads\/2022\/03\/environmental-nonprofit-24.png\u00a0\u00bb background_position=\u00a0\u00bbbottom_center\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb custom_margin=\u00a0\u00bb||\u00a0\u00bb custom_padding=\u00a0\u00bb12vw|10%|4vw|10%|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb110px||\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb2%\u00a0\u00bb border_radii=\u00a0\u00bb|10px|10px||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb box_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb box_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb box_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_font_size=\u00a0\u00bb60px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.4em\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb8px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.8em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_shadow_style=\u00a0\u00bbpreset3&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Vous souhaitez nous soutenir ?<\/h2>\n<h3><\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bb\/don\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbFaire une donation\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbgcid-3d183021-1ce3-4f9c-98e0-9842653824e6&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_color=\u00a0\u00bb#EFEFEF\u00a0\u00bb button_border_radius=\u00a0\u00bb25px\u00a0\u00bb button_border_width_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb button_text_shadow_style=\u00a0\u00bbpreset3&Prime; button_text_shadow_blur_strength=\u00a0\u00bb0em\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset3&Prime; box_shadow_vertical=\u00a0\u00bb6px\u00a0\u00bb box_shadow_blur=\u00a0\u00bb10px\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-3d183021-1ce3-4f9c-98e0-9842653824e6%22:%91%22button_bg_color%22,%22button_text_color__hover%22%93,%22gcid-3cfd0866-707b-4fb4-b8e2-1b167c11a155%22:%91%22button_bg_color__hover%22%93}\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_text_color__hover=\u00a0\u00bb#3ec637&Prime; button_text_shadow_color__hover_enabled=\u00a0\u00bboff|hover\u00a0\u00bb button_text_shadow_color__hover=\u00a0\u00bb#4bc938&Prime; button_border_width__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb button_border_width__hover=\u00a0\u00bb1px\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bbhttps:\/\/rookieslash.org\/home\/simpliquer\/\u00a0\u00bb button_text=\u00a0\u00bbD\u00e9couvrez comment vous pouvez vous impliquer ici\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bb\u00a0\u00bb button_text_phone=\u00a0\u00bbS&rsquo;impliquer\u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbRGBA(147,172,167,0.5)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb100px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos activit\u00e9s \u00e0 Gen\u00e8veLe potentiel social des sports de glisse et outdoor En offrant un acc\u00e8s aux sports de glisse et outdoor \u00e0 des jeunes en difficult\u00e9, nous offrons plus qu&rsquo;un moment de fun: c&rsquo;est aussi une \u00e9cole de vieLe skateboard, un brasseur social et une p\u00e9dagogie positive. Apprendre le skateboard n&rsquo;est pas facile.\u00a0Son apprentissage [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-28976","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rookieslash.org\/en\/wp-json\/wp\/v2\/pages\/28976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rookieslash.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rookieslash.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rookieslash.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rookieslash.org\/en\/wp-json\/wp\/v2\/comments?post=28976"}],"version-history":[{"count":166,"href":"https:\/\/rookieslash.org\/en\/wp-json\/wp\/v2\/pages\/28976\/revisions"}],"predecessor-version":[{"id":290871,"href":"https:\/\/rookieslash.org\/en\/wp-json\/wp\/v2\/pages\/28976\/revisions\/290871"}],"wp:attachment":[{"href":"https:\/\/rookieslash.org\/en\/wp-json\/wp\/v2\/media?parent=28976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}